{"id":18459,"date":"2017-06-05T17:32:04","date_gmt":"2017-06-05T17:32:04","guid":{"rendered":"http:\/\/aristidenajean.ch\/2017\/06\/05\/news-2\/"},"modified":"2017-09-05T09:34:01","modified_gmt":"2017-09-05T09:34:01","slug":"news-2","status":"publish","type":"post","link":"https:\/\/aristidenajean.ch\/en\/news-2\/","title":{"rendered":"Castello Sforzesco- &#8220;Vetri contemporanei al Castello Sforzesco a Milano &#8211; La collezione Bellini-Pezzoli &#8211; Mostra permanente&#8221;"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_single_image image=&#8221;19164&#8243; img_size=&#8221;large&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_single_image image=&#8221;19164&#8243; img_size=&#8221;large&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":2,"featured_media":18950,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[151],"tags":[],"class_list":["post-18459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publications"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Castello Sforzesco- &quot;Vetri contemporanei al Castello Sforzesco a Milano - La collezione Bellini-Pezzoli - Mostra permanente&quot; - Aristide Najean<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aristidenajean.ch\/news-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Castello Sforzesco- &quot;Vetri contemporanei al Castello Sforzesco a Milano - La collezione Bellini-Pezzoli - Mostra permanente&quot; - Aristide Najean\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_single_image image=&#8221;19164&#8243; img_size=&#8221;large&#8221;][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aristidenajean.ch\/news-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Aristide Najean\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-05T17:32:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-09-05T09:34:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aristidenajean.ch\/wp-content\/uploads\/2017\/06\/castellosforzesco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"murano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"murano\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/news-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/news-2\\\/\"},\"author\":{\"name\":\"murano\",\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/#\\\/schema\\\/person\\\/a683c03586f74c66c18f56452dfa061a\"},\"headline\":\"Castello Sforzesco- &#8220;Vetri contemporanei al Castello Sforzesco a Milano &#8211; La collezione Bellini-Pezzoli &#8211; Mostra permanente&#8221;\",\"datePublished\":\"2017-06-05T17:32:04+00:00\",\"dateModified\":\"2017-09-05T09:34:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/news-2\\\/\"},\"wordCount\":31,\"image\":{\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/news-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aristidenajean.ch\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/castellosforzesco.jpg\",\"articleSection\":[\"Publications\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/news-2\\\/\",\"url\":\"https:\\\/\\\/aristidenajean.ch\\\/news-2\\\/\",\"name\":\"Castello Sforzesco- \\\"Vetri contemporanei al Castello Sforzesco a Milano - La collezione Bellini-Pezzoli - Mostra permanente\\\" - Aristide Najean\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/news-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/news-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aristidenajean.ch\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/castellosforzesco.jpg\",\"datePublished\":\"2017-06-05T17:32:04+00:00\",\"dateModified\":\"2017-09-05T09:34:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/#\\\/schema\\\/person\\\/a683c03586f74c66c18f56452dfa061a\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/news-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aristidenajean.ch\\\/news-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/news-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aristidenajean.ch\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/castellosforzesco.jpg\",\"contentUrl\":\"https:\\\/\\\/aristidenajean.ch\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/castellosforzesco.jpg\",\"width\":500,\"height\":706},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/news-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aristidenajean.ch\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Castello Sforzesco- &#8220;Vetri contemporanei al Castello Sforzesco a Milano &#8211; La collezione Bellini-Pezzoli &#8211; Mostra permanente&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/#website\",\"url\":\"https:\\\/\\\/aristidenajean.ch\\\/\",\"name\":\"Aristide Najean\",\"description\":\"L&#039;Arte del vetro a Murano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aristidenajean.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aristidenajean.ch\\\/#\\\/schema\\\/person\\\/a683c03586f74c66c18f56452dfa061a\",\"name\":\"murano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf42bbf9eef4c5b5ab06ea7c89c3ad0e6fc6a9f08d2c2e53e10ea33ff5331337?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf42bbf9eef4c5b5ab06ea7c89c3ad0e6fc6a9f08d2c2e53e10ea33ff5331337?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf42bbf9eef4c5b5ab06ea7c89c3ad0e6fc6a9f08d2c2e53e10ea33ff5331337?s=96&d=mm&r=g\",\"caption\":\"murano\"},\"url\":\"https:\\\/\\\/aristidenajean.ch\\\/en\\\/author\\\/murano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Castello Sforzesco- \"Vetri contemporanei al Castello Sforzesco a Milano - La collezione Bellini-Pezzoli - Mostra permanente\" - Aristide Najean","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aristidenajean.ch\/news-2\/","og_locale":"en_US","og_type":"article","og_title":"Castello Sforzesco- \"Vetri contemporanei al Castello Sforzesco a Milano - La collezione Bellini-Pezzoli - Mostra permanente\" - Aristide Najean","og_description":"[vc_row][vc_column][vc_single_image image=&#8221;19164&#8243; img_size=&#8221;large&#8221;][\/vc_column][\/vc_row]","og_url":"https:\/\/aristidenajean.ch\/news-2\/","og_site_name":"Aristide Najean","article_published_time":"2017-06-05T17:32:04+00:00","article_modified_time":"2017-09-05T09:34:01+00:00","og_image":[{"width":500,"height":706,"url":"https:\/\/aristidenajean.ch\/wp-content\/uploads\/2017\/06\/castellosforzesco.jpg","type":"image\/jpeg"}],"author":"murano","twitter_card":"summary_large_image","twitter_misc":{"Written by":"murano"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aristidenajean.ch\/news-2\/#article","isPartOf":{"@id":"https:\/\/aristidenajean.ch\/news-2\/"},"author":{"name":"murano","@id":"https:\/\/aristidenajean.ch\/#\/schema\/person\/a683c03586f74c66c18f56452dfa061a"},"headline":"Castello Sforzesco- &#8220;Vetri contemporanei al Castello Sforzesco a Milano &#8211; La collezione Bellini-Pezzoli &#8211; Mostra permanente&#8221;","datePublished":"2017-06-05T17:32:04+00:00","dateModified":"2017-09-05T09:34:01+00:00","mainEntityOfPage":{"@id":"https:\/\/aristidenajean.ch\/news-2\/"},"wordCount":31,"image":{"@id":"https:\/\/aristidenajean.ch\/news-2\/#primaryimage"},"thumbnailUrl":"https:\/\/aristidenajean.ch\/wp-content\/uploads\/2017\/06\/castellosforzesco.jpg","articleSection":["Publications"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/aristidenajean.ch\/news-2\/","url":"https:\/\/aristidenajean.ch\/news-2\/","name":"Castello Sforzesco- \"Vetri contemporanei al Castello Sforzesco a Milano - La collezione Bellini-Pezzoli - Mostra permanente\" - Aristide Najean","isPartOf":{"@id":"https:\/\/aristidenajean.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aristidenajean.ch\/news-2\/#primaryimage"},"image":{"@id":"https:\/\/aristidenajean.ch\/news-2\/#primaryimage"},"thumbnailUrl":"https:\/\/aristidenajean.ch\/wp-content\/uploads\/2017\/06\/castellosforzesco.jpg","datePublished":"2017-06-05T17:32:04+00:00","dateModified":"2017-09-05T09:34:01+00:00","author":{"@id":"https:\/\/aristidenajean.ch\/#\/schema\/person\/a683c03586f74c66c18f56452dfa061a"},"breadcrumb":{"@id":"https:\/\/aristidenajean.ch\/news-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aristidenajean.ch\/news-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aristidenajean.ch\/news-2\/#primaryimage","url":"https:\/\/aristidenajean.ch\/wp-content\/uploads\/2017\/06\/castellosforzesco.jpg","contentUrl":"https:\/\/aristidenajean.ch\/wp-content\/uploads\/2017\/06\/castellosforzesco.jpg","width":500,"height":706},{"@type":"BreadcrumbList","@id":"https:\/\/aristidenajean.ch\/news-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aristidenajean.ch\/home\/"},{"@type":"ListItem","position":2,"name":"Castello Sforzesco- &#8220;Vetri contemporanei al Castello Sforzesco a Milano &#8211; La collezione Bellini-Pezzoli &#8211; Mostra permanente&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/aristidenajean.ch\/#website","url":"https:\/\/aristidenajean.ch\/","name":"Aristide Najean","description":"L&#039;Arte del vetro a Murano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aristidenajean.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/aristidenajean.ch\/#\/schema\/person\/a683c03586f74c66c18f56452dfa061a","name":"murano","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/bf42bbf9eef4c5b5ab06ea7c89c3ad0e6fc6a9f08d2c2e53e10ea33ff5331337?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf42bbf9eef4c5b5ab06ea7c89c3ad0e6fc6a9f08d2c2e53e10ea33ff5331337?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf42bbf9eef4c5b5ab06ea7c89c3ad0e6fc6a9f08d2c2e53e10ea33ff5331337?s=96&d=mm&r=g","caption":"murano"},"url":"https:\/\/aristidenajean.ch\/en\/author\/murano\/"}]}},"_links":{"self":[{"href":"https:\/\/aristidenajean.ch\/en\/wp-json\/wp\/v2\/posts\/18459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aristidenajean.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aristidenajean.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aristidenajean.ch\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aristidenajean.ch\/en\/wp-json\/wp\/v2\/comments?post=18459"}],"version-history":[{"count":4,"href":"https:\/\/aristidenajean.ch\/en\/wp-json\/wp\/v2\/posts\/18459\/revisions"}],"predecessor-version":[{"id":19169,"href":"https:\/\/aristidenajean.ch\/en\/wp-json\/wp\/v2\/posts\/18459\/revisions\/19169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aristidenajean.ch\/en\/wp-json\/wp\/v2\/media\/18950"}],"wp:attachment":[{"href":"https:\/\/aristidenajean.ch\/en\/wp-json\/wp\/v2\/media?parent=18459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aristidenajean.ch\/en\/wp-json\/wp\/v2\/categories?post=18459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aristidenajean.ch\/en\/wp-json\/wp\/v2\/tags?post=18459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}